{"id":460,"date":"2022-09-15T10:26:03","date_gmt":"2022-09-15T10:26:03","guid":{"rendered":"https:\/\/heimdall-gallery.com\/?page_id=460"},"modified":"2025-09-18T06:08:23","modified_gmt":"2025-09-18T06:08:23","slug":"identite","status":"publish","type":"page","link":"https:\/\/heimdall-gallery.com\/fr\/identite\/","title":{"rendered":"Identit\u00e9"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbHeader\u00a0\u00bb module_class=\u00a0\u00bbheader-section\u00a0\u00bb _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttp:\/\/heimdall-gallery.com\/wp-content\/uploads\/2023\/12\/philip-myrtorp-IVBTPa2lRa4-unspl-3.jpg\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row module_class=\u00a0\u00bbheader-row\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_cta title=\u00a0\u00bbL&rsquo;essence scandinave\u00a0\u00bb admin_label=\u00a0\u00bbHeader\u00a0\u00bb module_class=\u00a0\u00bbheader-module\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh1&Prime; use_background_color=\u00a0\u00bboff\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb900ms\u00a0\u00bb animation_delay=\u00a0\u00bb2ms\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb2%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb admin_label=\u00a0\u00bbQuote\u00a0\u00bb module_class=\u00a0\u00bbquote-section\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||50px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||0px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb75%\u00a0\u00bb width_tablet=\u00a0\u00bb90%\u00a0\u00bb width_phone=\u00a0\u00bb90%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bbmargin-bottom: 10px !important;\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bbmargin-bottom: 10px !important;\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||10px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||10px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb50px|||||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb10px||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Notre vision<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb2px|||||\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb5%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">La beaut\u00e9 de la Scandinavie r\u00e9side dans sa nature et ses habitants. \u00c0 travers l&rsquo;art, nos artistes traduisent une partie de ce que l&rsquo;on peut voir et ressentir dans cette r\u00e9gion mystique.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Fond\u00e9e avec la conviction que l\u2019art scandinave m\u00e9rite une place de choix en dehors de ses fronti\u00e8res, notre galerie est la seule en Europe \u00e0 se consacrer exclusivement \u00e0 cette sc\u00e8ne contemporaine.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Nous s\u00e9lectionnons avec exigence chaque \u0153uvre pour son caract\u00e8re unique, son raffinement et son pouvoir d\u2019\u00e9lever un int\u00e9rieur au rang d\u2019espace d\u2019exception.<\/p>\n<p data-start=\"1210\" data-end=\"1278\" style=\"text-align: justify;\">[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/heimdall-gallery.com\/wp-content\/uploads\/2025\/07\/Sandell_Mars-II_low-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbSandell_Mars II_low\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb60%\u00a0\u00bb width_tablet=\u00a0\u00bb58%\u00a0\u00bb width_phone=\u00a0\u00bb100%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb101px||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_duration=\u00a0\u00bb1200ms\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbQuote\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px|||||\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb10px||10px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb10px||10px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbAuthenticit\u00e9\u00a0\u00bb image_icon_width=\u00a0\u00bb88%\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb body_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_tablet=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p class=\"p1\">Des artistes s\u00e9lectionn\u00e9s pour leur sinc\u00e9rit\u00e9 et leur enracinement dans la culture nordique.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbImmersif\u00a0\u00bb image_icon_width=\u00a0\u00bb50%\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb body_text_align=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p class=\"p1\">Une esth\u00e9tique claire, lumineuse, qui laisse la mati\u00e8re et la lumi\u00e8re respirer.<\/p>\n<p data-start=\"869\" data-end=\"968\">[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbIntemporel\u00a0\u00bb image_icon_width=\u00a0\u00bb50%\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb body_text_align=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p class=\"p1\">Des pi\u00e8ces qui traversent les \u00e9poques sans se d\u00e9moder.<\/p>\n<p data-start=\"869\" data-end=\"968\">[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb background_blend=\u00a0\u00bboverlay\u00a0\u00bb min_height=\u00a0\u00bb523px\u00a0\u00bb custom_margin=\u00a0\u00bb-50px|||||\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; min_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb min_height_tablet=\u00a0\u00bb100%\u00a0\u00bb min_height_phone=\u00a0\u00bb100%\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb3_5,2_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px||||false|false\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb width_tablet=\u00a0\u00bb100%\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb width_phone=\u00a0\u00bb100%\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/heimdall-gallery.com\/wp-content\/uploads\/2025\/08\/Design-sans-titre-1-1.jpg\u00a0\u00bb title_text=\u00a0\u00bbDesign sans titre &#8211; 1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|5%||5%|false|false\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; custom_padding_phone=\u00a0\u00bb|5%||5%|false|false\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb custom_margin=\u00a0\u00bb79px|||0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|21px||0px|false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; border_width_right=\u00a0\u00bb1px\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px|||0px|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb border_width_right_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb border_width_right_tablet=\u00a0\u00bb0px\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; text_letter_spacing_tablet=\u00a0\u00bb0px\u00a0\u00bb text_letter_spacing_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|||0px|false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb border_width_right_phone=\u00a0\u00bb0px\u00a0\u00bb text_letter_spacing_phone=\u00a0\u00bb0px\u00a0\u00bb]<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Derri\u00e8re chaque \u0153uvre, une main de ma\u00eetre prolonge des traditions s\u00e9culaires, fa\u00e7onn\u00e9es par le climat, la nature et l\u2019exigence d\u2019un territoire.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Nos artistes scandinaves perp\u00e9tuent cette ma\u00eetrise rare, o\u00f9 chaque coup de pinceau raconte une histoire.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbParagraph\u00a0\u00bb module_class=\u00a0\u00bbparagraph-section dc_inverser_colonnes-section\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb60px|||||\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; custom_margin_tablet=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb20px||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; module_class=\u00a0\u00bbparagraph-row dc_inverser_colonnes-ligne\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb75%\u00a0\u00bb custom_margin=\u00a0\u00bb||30px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; custom_css_main_element=\u00a0\u00bbdisplay: flex;||align-items:center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb width_tablet=\u00a0\u00bb90%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; custom_css_main_element_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bbdisplay: block;\u00a0\u00bb width_phone=\u00a0\u00bb90%\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bbdisplay: block;\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bbmargin-bottom: 0px !important;\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; custom_css_main_element_phone=\u00a0\u00bbmargin-bottom: 0px !important;\u00a0\u00bb][et_pb_text module_class=\u00a0\u00bbparagraph-module\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.6em\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb5%\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb width_tablet=\u00a0\u00bb100%\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; custom_padding_tablet=\u00a0\u00bb30px||0px||false|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb width_phone=\u00a0\u00bb100%\u00a0\u00bb custom_padding_phone=\u00a0\u00bb30px||0px||false|false\u00a0\u00bb]<\/p>\n<p class=\"p1\">L\u2019art scandinave puise sa force dans la nature, la lumi\u00e8re et le silence. Il traduit une philosophie de vie o\u00f9 chaque d\u00e9tail compte et o\u00f9 la beaut\u00e9 s\u2019exprime dans la simplicit\u00e9.<\/p>\n<p class=\"p1\">Chaque pi\u00e8ce est plus qu\u2019un objet : c\u2019est le fruit d\u2019un savoir-faire patient, pr\u00e9cis et authentique.<\/p>\n<p class=\"p1\"><i>Une invitation \u00e0 ressentir cette harmonie.<\/i><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/heimdall-gallery.com\/wp-content\/uploads\/2025\/03\/Thengius_Daybreak_low-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbThengius_Daybreak_low\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb width=\u00a0\u00bb65%\u00a0\u00bb filter_saturate=\u00a0\u00bb110%\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; box_shadow_style=\u00a0\u00bbpreset1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb width_tablet=\u00a0\u00bb50%\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; width_phone=\u00a0\u00bb70%\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbParagraph\u00a0\u00bb module_class=\u00a0\u00bbparagraph-section\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb90px||100px|||\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px||20px||false|false\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; custom_margin_phone=\u00a0\u00bb0px||20px||false|false\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; module_class=\u00a0\u00bbparagraph-row\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb75%\u00a0\u00bb custom_margin=\u00a0\u00bb||30px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; custom_css_main_element=\u00a0\u00bbdisplay:flex;||align-items:center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb width_tablet=\u00a0\u00bb90%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bbdisplay: block;\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; width_phone=\u00a0\u00bb90%\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bbdisplay: block;\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/heimdall-gallery.com\/wp-content\/uploads\/2025\/09\/Portrait_Andreas_Fensby-scaled.jpeg\u00a0\u00bb title_text=\u00a0\u00bbPortrait_Andreas_Fensby\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb width=\u00a0\u00bb75%\u00a0\u00bb filter_brightness=\u00a0\u00bb110%\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb width_tablet=\u00a0\u00bb50%\u00a0\u00bb width_phone=\u00a0\u00bb70%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text module_class=\u00a0\u00bbparagraph-module\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.6em\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb5%\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb width_tablet=\u00a0\u00bb100%\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; width_phone=\u00a0\u00bb100%\u00a0\u00bb]<\/p>\n<p class=\"p1\">Fond\u00e9e par Andr\u00e9as Fensby, Heimdall Gallery na\u00eet en 2022 avec une ambition simple : ouvrir les portes de l\u2019art scandinave contemporain au-del\u00e0 de ses fronti\u00e8res.<\/p>\n<p class=\"p1\">Apr\u00e8s une Licence et un Master Litt\u00e9raire \u00e0 la Sorbonne et plusieurs ann\u00e9es de travail en galerie d&rsquo;art et mus\u00e9e, il fonde la galerie dans les Alpes, plus particuli\u00e8rement le Vercors, r\u00e9gion de son enfance.<\/p>\n<p class=\"p1\">Sa double nationalit\u00e9 franco-su\u00e9doise lui permet de r\u00e9aliser une s\u00e9lection artistique qui va habilement repr\u00e9senter l&rsquo;identit\u00e9 Scandinave \u00e0 l\u2019\u00e9tranger.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbContact\u00a0\u00bb module_class=\u00a0\u00bbcontact-section\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/heimdall-gallery.com\/wp-content\/uploads\/2025\/08\/Panorama_ateljen_low.jpg\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; background_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb background_color_gradient_stops_tablet=\u00a0\u00bbrgba(0,0,0,0.28) 0%|rgba(0,0,0,0.28) 100%\u00a0\u00bb use_background_color_gradient_tablet=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_overlays_image_tablet=\u00a0\u00bbon\u00a0\u00bb][et_pb_row module_class=\u00a0\u00bbcontact-row\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_cta title=\u00a0\u00bbD\u00e9couvrez une s\u00e9lection unique d\u2019\u0153uvres, disponibles exclusivement \u00e0 la galerie.\u00a0\u00bb button_url=\u00a0\u00bbhttps:\/\/heimdall-gallery.com\/fr\/artistes\/\u00a0\u00bb button_text=\u00a0\u00bbExplorez les \u0153uvres\u00a0\u00bb admin_label=\u00a0\u00bbContenu\u00a0\u00bb module_class=\u00a0\u00bbcontact-module text-link\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh3&Prime; header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb22px\u00a0\u00bb body_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb5%\u00a0\u00bb header_text_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre visionLa beaut\u00e9 de la Scandinavie r\u00e9side dans sa nature et ses habitants. \u00c0 travers l&rsquo;art, nos artistes traduisent une partie de ce que l&rsquo;on peut voir et ressentir dans cette r\u00e9gion mystique. Fond\u00e9e avec la conviction que l\u2019art scandinave m\u00e9rite une place de choix en dehors de ses fronti\u00e8res, notre galerie est la seule en Europe \u00e0 se consacrer exclusivement \u00e0 cette sc\u00e8ne contemporaine. Nous s\u00e9lectionnons avec exigence chaque \u0153uvre pour son caract\u00e8re unique, son raffinement et son pouvoir d\u2019\u00e9lever un int\u00e9rieur au rang d\u2019espace d\u2019exception. Des artistes s\u00e9lectionn\u00e9s pour leur sinc\u00e9rit\u00e9 et leur enracinement dans la culture nordique.Une esth\u00e9tique claire, lumineuse, qui laisse la mati\u00e8re et la lumi\u00e8re respirer. Des pi\u00e8ces qui traversent les \u00e9poques sans se d\u00e9moder. Derri\u00e8re chaque \u0153uvre, une main de ma\u00eetre prolonge des traditions s\u00e9culaires, fa\u00e7onn\u00e9es par le climat, la nature et l\u2019exigence d\u2019un territoire. Nos artistes scandinaves perp\u00e9tuent cette ma\u00eetrise rare, o\u00f9 chaque coup de pinceau raconte une histoire.L\u2019art scandinave puise sa force dans la nature, la lumi\u00e8re et le silence. Il traduit une philosophie de vie o\u00f9 chaque d\u00e9tail compte et o\u00f9 la beaut\u00e9 s\u2019exprime dans la simplicit\u00e9. Chaque pi\u00e8ce est plus qu\u2019un objet : c\u2019est le fruit d\u2019un savoir-faire patient, pr\u00e9cis [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"[et_pb_section fb_built=\"1\" admin_label=\"Header\" module_class=\"header-section\" _builder_version=\"4.17.4\" _module_preset=\"default\" background_image=\"https:\/\/heimdallprod.wpengine.com\/wp-content\/uploads\/2022\/10\/header-identity.jpg\" global_colors_info=\"{}\"][et_pb_row module_class=\"header-row\" _builder_version=\"4.17.4\" _module_preset=\"default\" background_enable_image=\"off\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_cta title=\"The passion\r\nof scandinavia\" admin_label=\"Header\" module_class=\"header-module\" _builder_version=\"4.17.4\" _module_preset=\"default\" header_level=\"h1\" animation_style=\"fade\" animation_duration=\"900ms\" animation_delay=\"2ms\" animation_starting_opacity=\"2%\" global_colors_info=\"{}\"][\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" admin_label=\"Quote\" module_class=\"quote-section\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_row module_class=\"quote-row\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text module_class=\"quote-module\" _builder_version=\"4.17.4\" _module_preset=\"default\" animation_style=\"slide\" animation_direction=\"bottom\" animation_duration=\"900ms\" animation_intensity_slide=\"5%\" global_colors_info=\"{}\"]\u201cAliquam tempus quam purus. Praesent consectetur molestie quam, ac vestibulum quam. Aliquam erat. \u201c[\/et_pb_text][et_pb_text admin_label=\"Andreas Fensby\" module_class=\"quote-andreas-module\" _builder_version=\"4.17.4\" _module_preset=\"default\" animation_style=\"slide\" animation_direction=\"bottom\" animation_duration=\"900ms\" animation_intensity_slide=\"5%\" global_colors_info=\"{}\"]Andreas Fensby[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" admin_label=\"Paragraph\" module_class=\"paragraph-section\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_row module_class=\"paragraph-row\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text module_class=\"paragraph-module\" _builder_version=\"4.17.4\" _module_preset=\"default\" animation_style=\"fade\" animation_duration=\"900ms\" animation_starting_opacity=\"5%\" global_colors_info=\"{}\"]\r\n\r\nCras a viverra neque, quis bibendum sem. Cras in sodales arcu. Vestibulum sed fringilla arcu, iaculis tincidunt tortor. Suspendisse potenti. Praesent sem neque, faucibus nec nibh et, euismod aliquet ante. Morbi arcu tellus, mattis ut fermentum molestie, dapibus quis lorem. Vivamus in erat non libero posuere placerat rhoncus sit amet diam. Donec odio diam, mollis vitae ultricies sed, dictum et turpis.\r\n\r\nNullam porta lectus eget semper iaculis. Maecenas pharetra imperdiet molestie. Quisque lorem mi, volutpat a magna a, elementum fringilla nunCras a viverra neque, quis bibendum sem. Cras in sodales arcu. Vestibulum sed fringilla arcu, iaculis tincidunt tortor. Suspendisse potenti. Praesent sem neque, faucibus nec nibh et, euismod aliquet ante. Morbi arcu tellus, mattis ut fermentum molestie, dapibus quis lorem. Vivamus in erat non libero posuere placerat rhoncus sit amet diam.\r\n\r\nDonec odio diam, mollis vitae ultricies sed, dictum et turpis. Nullam porta lectus eget semper iaculis.\r\n\r\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" admin_label=\"Images\" module_class=\"identity-img-section\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_row module_class=\"identity-img-row\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_image src=\"https:\/\/heimdallprod.wpengine.com\/wp-content\/uploads\/2022\/10\/identity-1.png\" title_text=\"identity-1\" module_class=\"identity-img-module\" _builder_version=\"4.17.4\" _module_preset=\"default\" animation_style=\"slide\" animation_direction=\"bottom\" animation_intensity_slide=\"2%\" global_colors_info=\"{}\"][\/et_pb_image][et_pb_image src=\"https:\/\/heimdallprod.wpengine.com\/wp-content\/uploads\/2022\/10\/identity-2.png\" title_text=\"identity-2\" module_class=\"identity-img-module\" _builder_version=\"4.17.4\" _module_preset=\"default\" animation_style=\"slide\" animation_direction=\"bottom\" animation_intensity_slide=\"2%\" global_colors_info=\"{}\"][\/et_pb_image][et_pb_image src=\"https:\/\/heimdallprod.wpengine.com\/wp-content\/uploads\/2022\/10\/identity-3.png\" title_text=\"identity-3\" module_class=\"identity-img-module\" _builder_version=\"4.17.4\" _module_preset=\"default\" animation_style=\"slide\" animation_direction=\"bottom\" animation_intensity_slide=\"2%\" global_colors_info=\"{}\"][\/et_pb_image][et_pb_image src=\"https:\/\/heimdallprod.wpengine.com\/wp-content\/uploads\/2022\/10\/identity-4.png\" title_text=\"identity-4\" module_class=\"identity-img-module\" _builder_version=\"4.17.4\" _module_preset=\"default\" animation_style=\"slide\" animation_direction=\"bottom\" animation_intensity_slide=\"2%\" global_colors_info=\"{}\"][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" admin_label=\"FAQ\" module_class=\"identity-faq-section\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_module=\"193\" saved_tabs=\"all\" global_colors_info=\"{}\"][et_pb_row module_class=\"identity-faq-row\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_blurb title=\"<span class=\"%22highlight%22\">How<\/span> does it work\" image=\"https:\/\/heimdallprod.wpengine.com\/wp-content\/uploads\/2022\/10\/icon-question-mark.svg\" admin_label=\"How does it work\" module_class=\"identity-faq-module\" _builder_version=\"4.17.4\" _module_preset=\"default\" animation_style=\"slide\" animation_direction=\"bottom\" animation_intensity_slide=\"5%\" animation=\"off\" global_colors_info=\"{}\"]\r\n\r\nPellentesque et diam vestibulum, placerat nulla in, pretium purus. Fusce eleifend vehicula nibh. Ut vel dui eget dui varius mollis. Aliquam lacinia odio non lacinia sodales.\r\n\r\n[\/et_pb_blurb][et_pb_blurb title=\"<span class=\"%22highlight%22\">What<\/span> warranty is there\" image=\"https:\/\/heimdallprod.wpengine.com\/wp-content\/uploads\/2022\/10\/checkmark.svg\" admin_label=\"What warranty\" module_class=\"identity-faq-module\" _builder_version=\"4.17.4\" _module_preset=\"default\" animation_style=\"slide\" animation_direction=\"bottom\" animation_intensity_slide=\"5%\" animation=\"off\" global_colors_info=\"{}\"]\r\n\r\nQuisque quis laoreet arcu. Vivamus ultrices at nisi quis auctor. Aliquam nec quam mauris. Suspendisse commodo pretium efficitur.\r\n\r\n[\/et_pb_blurb][et_pb_blurb title=\"<span class=\"%22highlight%22\">Where<\/span> are we\" image=\"https:\/\/heimdallprod.wpengine.com\/wp-content\/uploads\/2022\/10\/localisation.svg\" admin_label=\"Where are we\" module_class=\"identity-faq-module\" _builder_version=\"4.17.4\" _module_preset=\"default\" animation_style=\"slide\" animation_direction=\"bottom\" animation_intensity_slide=\"5%\" animation=\"off\" global_colors_info=\"{}\"]\r\n\r\nAll the arts are located in Grenoble, France.\r\n\r\n[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" admin_label=\"Contact\" module_class=\"contact-section\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_row module_class=\"contact-row\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.17.4\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_cta title=\"Want to know more about Scandinavian art?\" button_url=\"\/contact\/\" button_text=\"Contact us\" admin_label=\"Contenu\" module_class=\"contact-module text-link\" _builder_version=\"4.17.4\" _module_preset=\"default\" header_level=\"h3\" background_layout=\"light\" animation_style=\"fade\" animation_duration=\"900ms\" animation_starting_opacity=\"5%\" hover_enabled=\"0\" global_colors_info=\"{}\" sticky_enabled=\"0\"]\r\n\r\nWe will gladly share with you the passion that drives us and why we exist.\r\n\r\n[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section]","_et_gb_content_width":"","footnotes":""},"class_list":["post-460","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Identit\u00e9 - Heimdall Gallery<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/heimdall-gallery.com\/fr\/identite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Identit\u00e9 - Heimdall Gallery\" \/>\n<meta property=\"og:description\" content=\"Notre visionLa beaut\u00e9 de la Scandinavie r\u00e9side dans sa nature et ses habitants. \u00c0 travers l&#039;art, nos artistes traduisent une partie de ce que l&#039;on peut voir et ressentir dans cette r\u00e9gion mystique. Fond\u00e9e avec la conviction que l\u2019art scandinave m\u00e9rite une place de choix en dehors de ses fronti\u00e8res, notre galerie est la seule en Europe \u00e0 se consacrer exclusivement \u00e0 cette sc\u00e8ne contemporaine. Nous s\u00e9lectionnons avec exigence chaque \u0153uvre pour son caract\u00e8re unique, son raffinement et son pouvoir d\u2019\u00e9lever un int\u00e9rieur au rang d\u2019espace d\u2019exception. Des artistes s\u00e9lectionn\u00e9s pour leur sinc\u00e9rit\u00e9 et leur enracinement dans la culture nordique.Une esth\u00e9tique claire, lumineuse, qui laisse la mati\u00e8re et la lumi\u00e8re respirer. Des pi\u00e8ces qui traversent les \u00e9poques sans se d\u00e9moder. Derri\u00e8re chaque \u0153uvre, une main de ma\u00eetre prolonge des traditions s\u00e9culaires, fa\u00e7onn\u00e9es par le climat, la nature et l\u2019exigence d\u2019un territoire. Nos artistes scandinaves perp\u00e9tuent cette ma\u00eetrise rare, o\u00f9 chaque coup de pinceau raconte une histoire.L\u2019art scandinave puise sa force dans la nature, la lumi\u00e8re et le silence. Il traduit une philosophie de vie o\u00f9 chaque d\u00e9tail compte et o\u00f9 la beaut\u00e9 s\u2019exprime dans la simplicit\u00e9. Chaque pi\u00e8ce est plus qu\u2019un objet : c\u2019est le fruit d\u2019un savoir-faire patient, pr\u00e9cis [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/heimdall-gallery.com\/fr\/identite\/\" \/>\n<meta property=\"og:site_name\" content=\"Heimdall Gallery\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-18T06:08:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/heimdall-gallery.com\/wp-content\/uploads\/2025\/09\/Logo-Heimdall-Gallery.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/identite\\\/\",\"url\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/identite\\\/\",\"name\":\"Identit\u00e9 - Heimdall Gallery\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/#website\"},\"datePublished\":\"2022-09-15T10:26:03+00:00\",\"dateModified\":\"2025-09-18T06:08:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/identite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/identite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/identite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Identit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/\",\"name\":\"Heimdall Gallery\",\"description\":\"La beaut\u00e9 de la Scandinavie pour les passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/#organization\",\"name\":\"Heimdall Gallery\",\"url\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/heimdall-gallery.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/20220801_heimdall_logotype-bleu.jpg\",\"contentUrl\":\"https:\\\/\\\/heimdall-gallery.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/20220801_heimdall_logotype-bleu.jpg\",\"width\":800,\"height\":800,\"caption\":\"Heimdall Gallery\"},\"image\":{\"@id\":\"https:\\\/\\\/heimdall-gallery.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/heimdall.gallery\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Identit\u00e9 - Heimdall Gallery","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/heimdall-gallery.com\/fr\/identite\/","og_locale":"fr_FR","og_type":"article","og_title":"Identit\u00e9 - Heimdall Gallery","og_description":"Notre visionLa beaut\u00e9 de la Scandinavie r\u00e9side dans sa nature et ses habitants. \u00c0 travers l'art, nos artistes traduisent une partie de ce que l'on peut voir et ressentir dans cette r\u00e9gion mystique. Fond\u00e9e avec la conviction que l\u2019art scandinave m\u00e9rite une place de choix en dehors de ses fronti\u00e8res, notre galerie est la seule en Europe \u00e0 se consacrer exclusivement \u00e0 cette sc\u00e8ne contemporaine. Nous s\u00e9lectionnons avec exigence chaque \u0153uvre pour son caract\u00e8re unique, son raffinement et son pouvoir d\u2019\u00e9lever un int\u00e9rieur au rang d\u2019espace d\u2019exception. Des artistes s\u00e9lectionn\u00e9s pour leur sinc\u00e9rit\u00e9 et leur enracinement dans la culture nordique.Une esth\u00e9tique claire, lumineuse, qui laisse la mati\u00e8re et la lumi\u00e8re respirer. Des pi\u00e8ces qui traversent les \u00e9poques sans se d\u00e9moder. Derri\u00e8re chaque \u0153uvre, une main de ma\u00eetre prolonge des traditions s\u00e9culaires, fa\u00e7onn\u00e9es par le climat, la nature et l\u2019exigence d\u2019un territoire. Nos artistes scandinaves perp\u00e9tuent cette ma\u00eetrise rare, o\u00f9 chaque coup de pinceau raconte une histoire.L\u2019art scandinave puise sa force dans la nature, la lumi\u00e8re et le silence. Il traduit une philosophie de vie o\u00f9 chaque d\u00e9tail compte et o\u00f9 la beaut\u00e9 s\u2019exprime dans la simplicit\u00e9. Chaque pi\u00e8ce est plus qu\u2019un objet : c\u2019est le fruit d\u2019un savoir-faire patient, pr\u00e9cis [&hellip;]","og_url":"https:\/\/heimdall-gallery.com\/fr\/identite\/","og_site_name":"Heimdall Gallery","article_modified_time":"2025-09-18T06:08:23+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/heimdall-gallery.com\/wp-content\/uploads\/2025\/09\/Logo-Heimdall-Gallery.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/heimdall-gallery.com\/fr\/identite\/","url":"https:\/\/heimdall-gallery.com\/fr\/identite\/","name":"Identit\u00e9 - Heimdall Gallery","isPartOf":{"@id":"https:\/\/heimdall-gallery.com\/fr\/#website"},"datePublished":"2022-09-15T10:26:03+00:00","dateModified":"2025-09-18T06:08:23+00:00","breadcrumb":{"@id":"https:\/\/heimdall-gallery.com\/fr\/identite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/heimdall-gallery.com\/fr\/identite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/heimdall-gallery.com\/fr\/identite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/heimdall-gallery.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Identit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/heimdall-gallery.com\/fr\/#website","url":"https:\/\/heimdall-gallery.com\/fr\/","name":"Heimdall Gallery","description":"La beaut\u00e9 de la Scandinavie pour les passionn\u00e9s","publisher":{"@id":"https:\/\/heimdall-gallery.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/heimdall-gallery.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/heimdall-gallery.com\/fr\/#organization","name":"Heimdall Gallery","url":"https:\/\/heimdall-gallery.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/heimdall-gallery.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/heimdall-gallery.com\/wp-content\/uploads\/2025\/08\/20220801_heimdall_logotype-bleu.jpg","contentUrl":"https:\/\/heimdall-gallery.com\/wp-content\/uploads\/2025\/08\/20220801_heimdall_logotype-bleu.jpg","width":800,"height":800,"caption":"Heimdall Gallery"},"image":{"@id":"https:\/\/heimdall-gallery.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/heimdall.gallery\/"]}]}},"_links":{"self":[{"href":"https:\/\/heimdall-gallery.com\/fr\/wp-json\/wp\/v2\/pages\/460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heimdall-gallery.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/heimdall-gallery.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/heimdall-gallery.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/heimdall-gallery.com\/fr\/wp-json\/wp\/v2\/comments?post=460"}],"version-history":[{"count":41,"href":"https:\/\/heimdall-gallery.com\/fr\/wp-json\/wp\/v2\/pages\/460\/revisions"}],"predecessor-version":[{"id":9971,"href":"https:\/\/heimdall-gallery.com\/fr\/wp-json\/wp\/v2\/pages\/460\/revisions\/9971"}],"wp:attachment":[{"href":"https:\/\/heimdall-gallery.com\/fr\/wp-json\/wp\/v2\/media?parent=460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}